{"id":28329,"date":"2026-04-20T14:52:25","date_gmt":"2026-04-20T12:52:25","guid":{"rendered":"https:\/\/musicdirectory.ch\/community-board\/"},"modified":"2026-05-12T13:52:10","modified_gmt":"2026-05-12T11:52:10","slug":"community-board","status":"publish","type":"page","link":"https:\/\/musicdirectory.ch\/de\/community-board\/","title":{"rendered":"Community Board"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center has-xlarge-font-size\">Poste, was du anbietest \u2013 oder finde, hier was du suchst.<\/h2>\n\n<p>Unser Community Board steht allen offen, unabh\u00e4ngig vom Geschlecht. Hier kannst du zum Beispiel nach einer neuen Tourmanager*in suchen, deine alte Gitarre verkaufen, Gesangsunterricht oder Konzertfotografie anbieten und vieles mehr.<\/p>\n\n<p><p>Falls dir was auff\u00e4llt, das nicht in Ordnung ist und nicht unseren <a href=\"#community-Richtlinien\" target=\"_blank\" rel=\"noopener\" data-mce-href=\"#community-Richtlinien\">Community-Richtlinien<\/a> entspricht, schreibe bitte an <a class=\"decorated-link cursor-pointer\" href=\"&#x6d;&#x61;&#x69;&#x6c;&#x74;&#x6f;&#x3a;&#x61;&#x64;&#x6d;&#x69;&#x6e;&#x40;&#x6d;&#117;&#115;&#105;&#99;&#100;&#105;&#114;&#101;&#99;&#116;&#111;ry&#46;ch\" target=\"_blank\" rel=\"noopener\" data-start=\"112\" data-end=\"135\" data-mce-href=\"&#x6d;&#x61;&#x69;&#x6c;&#x74;&#x6f;&#x3a;&#x61;&#100;&#109;&#105;&#110;&#64;&#109;&#117;sicd&#x69;&#x72;&#x65;&#x63;&#x74;&#x6f;&#x72;&#x79;&#x2e;&#99;&#104;\">&#97;d&#x6d;i&#x6e;&#64;&#x6d;&#117;&#x73;&#105;c&#x64;i&#x72;&#101;&#x63;&#116;&#x6f;&#114;&#x79;&#46;c&#x68;.<\/a><\/p><\/p>\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-fc4fd283 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-black-color has-mauve-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/musicdirectory.ch\/de\/create-post\/\">Inserat erstellen<\/a><\/div>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"postTeaser__wrapper\">\n\n  <div class=\"postTeaser__search\">\n    <div class=\"facetwp-facet facetwp-facet-facet_search facetwp-type-search\" data-name=\"facet_search\" data-type=\"search\"><\/div>\n  <\/div>\n\n  <div class=\"postTeaser__filters\">\n\n    <button type=\"button\" name=\"button\" class=\"postTeaser__filtersButton\" aria-expanded=\"false\" aria-controls=\"project_filter\">\n      Filter Inserate\n      <span class=\"postTeaser__filtersButton--iconFilter postTeaser__filtersButton--icon\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1080 1080\">\n  <g fill=\"#000\" fill-rule=\"nonzero\">\n    <path d=\"M1080 486v108H826.69C804.612 656.625 745.081 702 675 702s-130.08-45.375-152.29-108H0V486h522.71c22.219-62.625 81.609-108 152.29-108s129.61 45.375 151.69 108zM1080 864v108H556.69c-22.078 62.625-81.609 108-151.69 108s-130.08-45.375-152.29-108H0V864h252.71c22.219-62.625 81.609-108 152.29-108s129.61 45.375 151.69 108zM1080 108v108H556.69C534.612 278.625 475.081 324 405 324s-130.08-45.375-152.29-108H0V108h252.71C274.929 45.375 334.319 0 405 0s129.61 45.375 151.69 108z\"\/>\n  <\/g>\n<\/svg>      <\/span>\n      <span class=\"postTeaser__filtersButton--iconClose postTeaser__filtersButton--icon \">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 4603 4603\" fill-rule=\"evenodd\" clip-rule=\"evenodd\" shape-rendering=\"geometricPrecision\" text-rendering=\"geometricPrecision\" image-rendering=\"optimizeQuality\">\n  <path fill-rule=\"nonzero\" d=\"M0 3757l1455-1456L0 846 846 0l1455 1455L3757 0l846 846-1455 1455 1455 1456-846 846-1456-1455L846 4603z\"\/>\n<\/svg>      <\/span>\n    <\/button>\n\n    <div class=\"postTeaser__filtersContent\" id=\"project_filter\">\n      \n      <div class=\"postTeaser__filtersItems\">\n\n        \n\n        \n          \n          \n                    \n        \n          \n          \n                    \n        \n          \n          \n                    \n              <\/div>\n\n\n      <button type=\"button\" name=\"button\" class=\"postTeaser__filtersResultButton\" aria-expanded=\"true\" aria-controls=\"project_filter\">\n        <div class=\"facetwp-facet facetwp-facet-post_count facetwp-type-pager\" data-name=\"post_count\" data-type=\"pager\"><\/div>\n      \n        <span class=\"postTeaser__filtersButton--iconClose postTeaser__filtersButton--icon \">\n          <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 4603 4603\" fill-rule=\"evenodd\" clip-rule=\"evenodd\" shape-rendering=\"geometricPrecision\" text-rendering=\"geometricPrecision\" image-rendering=\"optimizeQuality\">\n  <path fill-rule=\"nonzero\" d=\"M0 3757l1455-1456L0 846 846 0l1455 1455L3757 0l846 846-1455 1455 1455 1456-846 846-1456-1455L846 4603z\"\/>\n<\/svg>        <\/span>\n      <\/button>\n    <\/div>\n\n  <\/div>\n\n  <div class=\"facetwp-template postTeaser__itemsWrapper\">\n                  <div class=\"search-no-results\">\n  <h2 class=\"search-no-results__title\"><span class=\"search-no-results__titleText\"> Wir haben leider nichts gefunden f\u00fcr <\/span> <div class=\"facetwp-selections\"><\/div><\/h2>\n\n  <h3 class=\"search-no-results__tipps\">Tipps f\u00fcr deine Suche:<\/h3>\n  <ul class=\"search-no-results__list\">\n    <li class=\"search-no-results__listItem\">Pr\u00fcfe ob du alle W\u00f6rter richtig geschrieben hast<\/li>\n    <li class=\"search-no-results__listItem\">Versuche einen anderen Suchbegriff<\/li>\n    <li class=\"search-no-results__listItem\">Versuche einen allgemeineren Suchbegriff<\/li>\n  <\/ul>\n<\/div>\n                  \n              <\/div>\n\n    \n\n  <\/div>\n<\/div>\n<p>Du findest nicht, wonach du suchst? Erstelle hier dein eigenes Inserat \u2013 ganz einfach!<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-black-color has-mauve-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/musicdirectory.ch\/de\/create-post\/\">Inserat erstellen<\/a><\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Poste, was du anbietest \u2013 oder finde, hier was du suchst. Unser Community Board steht allen offen, unabh\u00e4ngig vom Geschlecht. Hier kannst du zum Beispiel nach einer neuen Tourmanager*in suchen, deine alte Gitarre verkaufen, Gesangsunterricht oder Konzertfotografie anbieten und vieles mehr. Falls dir was auff\u00e4llt, das nicht in Ordnung ist und nicht unseren Community-Richtlinien entspricht, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"2960,5519,3562,4546,6288,2280","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-28329","page","type-page","status-publish","hentry"],"acf":[],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"musicdirectory.ch","distributor_original_site_url":"https:\/\/musicdirectory.ch\/de\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/pages\/28329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/comments?post=28329"}],"version-history":[{"count":6,"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/pages\/28329\/revisions"}],"predecessor-version":[{"id":28528,"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/pages\/28329\/revisions\/28528"}],"wp:attachment":[{"href":"https:\/\/musicdirectory.ch\/de\/wp-json\/wp\/v2\/media?parent=28329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}